{"id":1151,"count":1,"description":"","link":"https:\/\/sdgnews.com\/fr\/tag\/climate-research\/","name":"Climate Research","slug":"climate-research","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Climate Research Archives - SDG News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sdgnews.com\/fr\/tag\/climate-research\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Climate Research Archives - SDG News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sdgnews.com\/fr\/tag\/climate-research\/\" \/>\n<meta property=\"og:site_name\" content=\"SDG News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sdgnews.com\\\/tag\\\/climate-research\\\/\",\"url\":\"https:\\\/\\\/sdgnews.com\\\/tag\\\/climate-research\\\/\",\"name\":\"Climate Research Archives - SDG News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sdgnews.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sdgnews.com\\\/tag\\\/climate-research\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sdgnews.com\\\/tag\\\/climate-research\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sdgnews.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Climate Research\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sdgnews.com\\\/#website\",\"url\":\"https:\\\/\\\/sdgnews.com\\\/\",\"name\":\"SDG News\",\"description\":\"SDG News Supports the Sustainable Development Goals\",\"publisher\":{\"@id\":\"https:\\\/\\\/sdgnews.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sdgnews.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sdgnews.com\\\/#organization\",\"name\":\"SDG News\",\"url\":\"https:\\\/\\\/sdgnews.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sdgnews.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sdgnews.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Untitled-design-2.png\",\"contentUrl\":\"https:\\\/\\\/sdgnews.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Untitled-design-2.png\",\"width\":500,\"height\":246,\"caption\":\"SDG News\"},\"image\":{\"@id\":\"https:\\\/\\\/sdgnews.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Climate Research Archives - SDG News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sdgnews.com\/fr\/tag\/climate-research\/","og_locale":"fr_FR","og_type":"article","og_title":"Climate Research Archives - SDG News","og_url":"https:\/\/sdgnews.com\/fr\/tag\/climate-research\/","og_site_name":"SDG News","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sdgnews.com\/tag\/climate-research\/","url":"https:\/\/sdgnews.com\/tag\/climate-research\/","name":"Climate Research Archives - SDG News","isPartOf":{"@id":"https:\/\/sdgnews.com\/#website"},"breadcrumb":{"@id":"https:\/\/sdgnews.com\/tag\/climate-research\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/sdgnews.com\/tag\/climate-research\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sdgnews.com\/"},{"@type":"ListItem","position":2,"name":"Climate Research"}]},{"@type":"WebSite","@id":"https:\/\/sdgnews.com\/#website","url":"https:\/\/sdgnews.com\/","name":"SDG News","description":"SDG News Supports the Sustainable Development Goals","publisher":{"@id":"https:\/\/sdgnews.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sdgnews.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sdgnews.com\/#organization","name":"SDG News","url":"https:\/\/sdgnews.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sdgnews.com\/#\/schema\/logo\/image\/","url":"https:\/\/sdgnews.com\/wp-content\/uploads\/2024\/03\/Untitled-design-2.png","contentUrl":"https:\/\/sdgnews.com\/wp-content\/uploads\/2024\/03\/Untitled-design-2.png","width":500,"height":246,"caption":"SDG News"},"image":{"@id":"https:\/\/sdgnews.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sdgnews.com\/fr\/wp-json\/wp\/v2\/tags\/1151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sdgnews.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sdgnews.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sdgnews.com\/fr\/wp-json\/wp\/v2\/posts?tags=1151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}